{"id":94169,"date":"2026-06-11T12:01:19","date_gmt":"2026-06-11T10:01:19","guid":{"rendered":"https:\/\/chk-de.org\/?p=94169"},"modified":"2026-07-15T14:06:34","modified_gmt":"2026-07-15T12:06:34","slug":"dihk-china-business-forum-2026","status":"publish","type":"post","link":"https:\/\/chk-de.org\/de\/dihk-china-business-forum-2026\/","title":{"rendered":"DIHK China Business Forum 2026"},"content":{"rendered":"<p><span style=\"color: #000000;\">Am 11. Juni 2026 veranstaltete das chinesische Handelsministerium gemeinsam mit der Deutschen Industrie- und Handelskammer (DIHK) das erste DIHK China Business Forum 2026 unter dem Motto \u201eExport to China\u201c im Haus der Deutschen Wirtschaft. Besucht wurde die Veranstaltung unter anderem von Ling Ji, Vizehandelsminister von China und stellvertretender Beauftragter f\u00fcr internationale Handelsverhandlungen, dem Staatssekret\u00e4r des Bundesministeriums f\u00fcr Wirtschaft und Energie Dr. Thomas Steffen und Dr. Nicole Renvert, Bereichsleiterin f\u00fcr Internationale M\u00e4rkte bei der DIHK.<\/span><\/p>\n<p><span style=\"color: #000000;\">In seiner Rede erkl\u00e4rte Ling Ji, dass China und Deutschland an Offenheit, Zusammenarbeit, gegenseitigem Respekt und Vertrauen festhielten. Die wirtschaftliche Zusammenarbeit zwischen China und Deutschland sei nicht nur ein \u201eAnker f\u00fcr Stabilit\u00e4t\u201c und ein \u201eMotor\u201c f\u00fcr die bilateralen Beziehungen, sondern trage auch ma\u00dfgeblich zu der gesunden Entwicklung der wirtschaftlich-handelspolitischen Beziehungen zwischen China und der EU bei. Bez\u00fcglich des Handelsdefizits, welches Deutschland gegen\u00fcber China verzeichnet, \u00e4u\u00dferte er sich zuversichtlich: \u201eWir haben volles Verst\u00e4ndnis f\u00fcr die Besorgnis der deutschen Seite hinsichtlich des Handelsungleichgewichts, doch der Wechsel zwischen \u00dcberschuss und Defizit ist ganz normal. (\u2026) Ich bin \u00fcberzeugt, dass es nur eine Frage der Zeit ist, bis sich der bilaterale Handel ausgleicht, solange beide Seiten \u2013 China und Deutschland \u2013 ihre M\u00e4rkte f\u00fcreinander offenhalten.\u201c<\/span><\/p>\n<p><span style=\"color: #000000;\">Dr. Thomas Steffen, Staatssekret\u00e4r im Bundesministerium f\u00fcr Wirtschaft und Energie, betonte die Gemeinsamkeiten und den offenen Dialog zwischen China und Deutschland, appellierte hinsichtlich des Handelsdefizits aber auch daran, \u201enachhaltige, f\u00fcr beide Seiten vorteilhafte Wirtschafts- und Handelsbeziehungen aufzubauen.\u201c<\/span><\/p>\n<p><span style=\"color: #000000;\">Au\u00dferdem warb die China International Import Expo Administration f\u00fcr die 9. China International Import Expo, die Industrial and Commercial Bank of China stellte Ma\u00dfnahmen zur finanziellen Unterst\u00fctzung vor, und der Verband der Maschinenbau- und Elektroindustrie informierte \u00fcber die Nachfrage auf dem chinesischen Markt sowie \u00fcber Kooperationsabsichten. An der Veranstaltung nahmen rund 200 Unternehmerinnen und Unternehmer sowie Vertreterinnen und Vertreter von Wirtschaftsverb\u00e4nden und Regierungsstellen aus China und Deutschland teil.<\/span><\/p>\n\n<div class=\"lightbox gallery has-4-columns\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n  <div class=\"gallery__header size-5 fontw-l co-greyborder lh-1 divider\">\n    <span class=\"co-greytext\">Galerie<\/span>\n  <\/div>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04701-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04701-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04701-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04701-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04702-scaled.jpg\" data-size=\"2560,1810\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04702-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04702-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04702-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04753-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04753-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04753-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04753-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04761-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04761-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04761-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04761-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04786-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04786-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04786-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04786-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04788-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04788-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04788-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04788-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04797-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04797-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04797-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04797-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04803-scaled.jpg\" data-size=\"2560,1828\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04803-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04803-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04803-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04695-scaled.jpg\" data-size=\"2560,1920\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04695-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04695-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC04695-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0756-scaled.jpg\" data-size=\"2560,1702\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0756-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0756-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0756-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n    <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"gallery__item br-s\">\n    <a itemprop=\"contentUrl\" href=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0802-scaled.jpg\" data-size=\"2560,1702\" data-caption=\"\">\n      <img\n        itemprop=\"thumbnail\"\n        src=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0802-scaled.jpg\"\n        srcset=\"https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0802-scaled.jpg, https:\/\/chk-de.org\/app\/uploads\/2026\/07\/DSC_0802-scaled.jpg 2x\"\n        alt=\"\">\n    <\/a>\n  <\/figure>\n  <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Am 11. Juni 2026 veranstaltete das chinesische Handelsministerium gemeinsam mit der Deutschen Industrie- und Handelskammer (DIHK) das erste DIHK China Business Forum 2026 unter dem Motto \u201eExport to China\u201c im Haus der Deutschen Wirtschaft. Besucht wurde die Veranstaltung unter anderem von Ling Ji, Vizehandelsminister von China und stellvertretender Beauftragter f\u00fcr internationale Handelsverhandlungen, dem Staatssekret\u00e4r des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":94178,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35],"tags":[],"_links":{"self":[{"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/posts\/94169"}],"collection":[{"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/comments?post=94169"}],"version-history":[{"count":2,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/posts\/94169\/revisions"}],"predecessor-version":[{"id":94194,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/posts\/94169\/revisions\/94194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/media\/94178"}],"wp:attachment":[{"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/media?parent=94169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/categories?post=94169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chk-de.org\/de\/wp-json\/wp\/v2\/tags?post=94169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}